{"id":3527,"date":"2019-10-05T16:13:26","date_gmt":"2019-10-05T22:13:26","guid":{"rendered":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg"},"modified":"2019-10-05T16:13:26","modified_gmt":"2019-10-05T22:13:26","slug":"cropped-img_4291-jpeg","status":"inherit","type":"attachment","link":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/","title":{"rendered":"cropped-IMG_4291.jpeg"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"media_tag":[],"class_list":["post-3527","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Tony Henrie\"\/>\n\t<meta name=\"google-site-verification\" content=\"65PxVvnpA2gASWRFYtSyxkBi5YS_nbUIIS_z-XCz8yI\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Western Trail Rider\" \/>\n\t\t<meta property=\"og:type\" content=\"activity\" \/>\n\t\t<meta property=\"og:title\" content=\"cropped-IMG_4291.jpeg | Western Trail Rider\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"354492621331149\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1785851186\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@westerntrail\" \/>\n\t\t<meta name=\"twitter:title\" content=\"cropped-IMG_4291.jpeg | Western Trail Rider\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@westerntrail\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#listItem\",\"name\":\"cropped-IMG_4291.jpeg\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#listItem\",\"position\":2,\"name\":\"cropped-IMG_4291.jpeg\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#itempage\",\"url\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/\",\"name\":\"cropped-IMG_4291.jpeg | Western Trail Rider\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/blog\\\/author\\\/tony-henrie\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/blog\\\/author\\\/tony-henrie\\\/#author\"},\"datePublished\":\"2019-10-05T16:13:26-06:00\",\"dateModified\":\"2019-10-05T16:13:26-06:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/#organization\",\"name\":\"Western Trail Rider\",\"description\":\"For horse and mule packing, camping, and trail riding in the western United States\",\"url\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/westerntrailrider.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Western-Trail-Rider-Final3.5-1024x791.jpg?fit=1024%2C791&ssl=1\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#organizationLogo\",\"width\":1024,\"height\":791},\"image\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/westerntrailrider?ref=hl\",\"https:\\\/\\\/twitter.com\\\/westerntrail\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/blog\\\/author\\\/tony-henrie\\\/#author\",\"url\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/blog\\\/author\\\/tony-henrie\\\/\",\"name\":\"Tony Henrie\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/cropped-img_4291-jpeg\\\/#authorImage\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/75d9be94c8ce523acfb992e65e1e8425?s=96&#038;r=pg&#038;d=mm\",\"width\":96,\"height\":96,\"caption\":\"Tony Henrie\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/\",\"name\":\"Western Trail Rider\",\"description\":\"For horse and mule packing, camping, and trail riding in the western United States\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/westerntrailrider.com\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"cropped-IMG_4291.jpeg | Western Trail Rider","description":"","canonical_url":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"65PxVvnpA2gASWRFYtSyxkBi5YS_nbUIIS_z-XCz8yI","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/westerntrailrider.com\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/westerntrailrider.com\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#listItem","name":"cropped-IMG_4291.jpeg"}},{"@type":"ListItem","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#listItem","position":2,"name":"cropped-IMG_4291.jpeg","previousItem":{"@type":"ListItem","@id":"https:\/\/westerntrailrider.com\/wordpress#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#itempage","url":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/","name":"cropped-IMG_4291.jpeg | Western Trail Rider","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#breadcrumblist"},"author":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/blog\/author\/tony-henrie\/#author"},"creator":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/blog\/author\/tony-henrie\/#author"},"datePublished":"2019-10-05T16:13:26-06:00","dateModified":"2019-10-05T16:13:26-06:00"},{"@type":"Organization","@id":"https:\/\/westerntrailrider.com\/wordpress\/#organization","name":"Western Trail Rider","description":"For horse and mule packing, camping, and trail riding in the western United States","url":"https:\/\/westerntrailrider.com\/wordpress\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2018\/09\/Western-Trail-Rider-Final3.5-1024x791.jpg?fit=1024%2C791&ssl=1","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#organizationLogo","width":1024,"height":791},"image":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/westerntrailrider?ref=hl","https:\/\/twitter.com\/westerntrail"]},{"@type":"Person","@id":"https:\/\/westerntrailrider.com\/wordpress\/blog\/author\/tony-henrie\/#author","url":"https:\/\/westerntrailrider.com\/wordpress\/blog\/author\/tony-henrie\/","name":"Tony Henrie","image":{"@type":"ImageObject","@id":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/#authorImage","url":"\/\/www.gravatar.com\/avatar\/75d9be94c8ce523acfb992e65e1e8425?s=96&#038;r=pg&#038;d=mm","width":96,"height":96,"caption":"Tony Henrie"}},{"@type":"WebSite","@id":"https:\/\/westerntrailrider.com\/wordpress\/#website","url":"https:\/\/westerntrailrider.com\/wordpress\/","name":"Western Trail Rider","description":"For horse and mule packing, camping, and trail riding in the western United States","inLanguage":"en-US","publisher":{"@id":"https:\/\/westerntrailrider.com\/wordpress\/#organization"}}]},"og:locale":"en_US","og:site_name":"Western Trail Rider","og:type":"activity","og:title":"cropped-IMG_4291.jpeg | Western Trail Rider","og:url":"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/","fb:app_id":"354492621331149","fb:admins":"1785851186","og:image":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg","og:image:secure_url":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg","og:image:width":4032,"og:image:height":3024,"twitter:card":"summary","twitter:site":"@westerntrail","twitter:title":"cropped-IMG_4291.jpeg | Western Trail Rider","twitter:creator":"@westerntrail","twitter:image":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/IMG_4291.jpeg"},"aioseo_meta_data":{"post_id":"3527","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"limit_modified_date":false,"created":"2020-12-20 22:41:04","updated":"2026-06-27 10:03:18","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"filename":"cropped-IMG_4291.jpeg","filesize":190324,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a33SNi-UT","jetpack_likes_enabled":true,"description":{"rendered":"\r\n\t<!-- sfs forms added to the_content - adding as a comment so that it will not display, but will it fool spammers?\r\n\t<br>\r\n\t<br>\r\n\t<form action=\"https:\/\/westerntrailrider.com\/wordpress\/wp-comments-post.php\" method=\"post\" id=\"commentform1\">\r\n\t<p><input name=\"author\" id=\"author\" value=\"\" size=\"22\"  aria-required=\"true\" type=\"text\">\r\n\t<label for=\"author\"><small>Name (required)<\/small><\/label><\/p>\r\n\r\n\t<p><input name=\"email\" id=\"email\" value=\"\" size=\"22\"  aria-required=\"true\" type=\"text\">\r\n\t<label for=\"email\"><small>Mail (will not be published) (required)<\/small><\/label><\/p>\r\n\r\n\t<p><input name=\"url\" id=\"url\" value=\"\" size=\"22\" type=\"text\">\r\n\t<label for=\"url\"><small>Website<\/small><\/label><\/p>\r\n\t<p><textarea name=\"comment\" id=\"comment\" cols=\"58\" rows=\"10\" ><\/textarea><\/p>\r\n\r\n\t<p>\r\n\t<input name=\"comment_post_ID\" value=\"3527\" id=\"comment_post_ID\" type=\"hidden\">\r\n\t<input name=\"comment_parent\" id=\"comment_parent\" value=\"0\" type=\"hidden\">\r\n\t<\/p>\r\n\r\n\t<p><input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"494801dd2f\" type=\"hidden\"><\/p>\r\n\t<\/form>\r\n\r\n\t<form id=\"setupform1\" method=\"post\" action=\"wp-signup.php\" >\r\n\r\n\t<input type=\"hidden\" name=\"stage\" value=\"validate-user-signup\"   \/>\r\n\t<p ><input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"494801dd2f\" type=\"hidden\"><\/p>\t\t\r\n\t<p>\r\n\t<input id=\"signupblog\" type=\"radio\" name=\"signup_for\" value=\"blog\"  checked='checked' \/>\r\n\t<label class=\"checkbox\" for=\"signupblog\">Gimme a site!<\/label>\r\n\t<br \/>\r\n\t<input id=\"signupuser\" type=\"radio\" name=\"signup_for\" value=\"user\"  \/>\r\n\t<label class=\"checkbox\" for=\"signupuser\">Just a username, please.<\/label>\r\n\t<\/p>\r\n\t<\/form>\r\n\r\n\t<form name=\"loginform1\" id=\"loginform1\" action=\"https:\/\/westerntrailrider.com\/wordpress\/wp-login.php\" method=\"post\">\r\n\t<p>\r\n\t<label for=\"user_login\">User Name<br \/>\r\n\t<input type=\"text\" name=\"log\"  value=\"\" size=\"20\"  \/><\/label>\r\n\t<\/p>\r\n\t<p>\r\n\t<label for=\"user_pass\">Password<br \/>\r\n\t<input type=\"password\" name=\"pwd\"  value=\"\" size=\"20\"  \/><\/label>\r\n\t<\/p>\r\n\t<p class=\"forgetmenot\"><label for=\"rememberme\"><input name=\"rememberme\" type=\"checkbox\" checked=\"checked\"  value=\"494801dd2f\"  \/>Remember Me<\/label><\/p>\r\n\t<p class=\"submit\">\r\n\t<input type=\"hidden\" name=\"testcookie\" value=\"1\" \/>\r\n\t<\/p>\r\n\t<input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"494801dd2f\" type=\"hidden\">\r\n\t<\/form>\r\n\r\n\r\n\r\n\t-->\r\n\t<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"163\" src=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=300%2C163&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?w=1260&amp;ssl=1 1260w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?resize=300%2C163&amp;ssl=1 300w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?resize=768%2C416&amp;ssl=1 768w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?w=948&amp;ssl=1 948w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"3527\" data-permalink=\"https:\/\/westerntrailrider.com\/wordpress\/cropped-img_4291-jpeg\/\" data-orig-file=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=1260%2C683&amp;ssl=1\" data-orig-size=\"1260,683\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1569176289&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.6&quot;,&quot;iso&quot;:&quot;20&quot;,&quot;shutter_speed&quot;:&quot;0.0083333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"cropped-IMG_4291.jpeg\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=474%2C257&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1260,"height":683,"file":"2019\/10\/cropped-IMG_4291.jpeg","sizes":{"thumbnail":{"file":"cropped-IMG_4291-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?resize=150%2C150&ssl=1"},"medium":{"file":"cropped-IMG_4291-300x163.jpeg","width":300,"height":163,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=300%2C163&ssl=1"},"medium_large":{"file":"cropped-IMG_4291-768x416.jpeg","width":768,"height":416,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=474%2C257&ssl=1"},"post-thumbnail":{"file":"cropped-IMG_4291-672x372.jpeg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?resize=672%2C372&ssl=1"},"twentyfourteen-full-width":{"file":"cropped-IMG_4291-1038x576.jpeg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?resize=1038%2C576&ssl=1"},"full":{"file":"cropped-IMG_4291.jpeg?fit=1260%2C683&ssl=1","width":1260,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg?fit=1260%2C683&ssl=1"}},"image_meta":{"aperture":"2.8","credit":"","camera":"iPhone 7 Plus","caption":"","created_timestamp":"1569176289","copyright":"","focal_length":"6.6","iso":"20","shutter_speed":"0.0083333333333333","title":"","orientation":"1","keywords":[]},"attachment_parent":3516},"post":null,"source_url":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2019\/10\/cropped-IMG_4291.jpeg","jetpack_videopress_guid":"","jetpack_videopress":{"title":"cropped-IMG_4291.jpeg","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media\/3527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3527"}],"wp:term":[{"taxonomy":"media_tag","embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media_tag?post=3527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}