{"id":94,"date":"2013-02-05T13:52:02","date_gmt":"2013-02-05T18:52:02","guid":{"rendered":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg"},"modified":"2013-02-05T13:52:02","modified_gmt":"2013-02-05T18:52:02","slug":"2012-10-27-19-18-39-1024x576","status":"inherit","type":"attachment","link":"https:\/\/westerntrailrider.com\/wordpress\/2012-10-27-19-18-39-1024x576\/","title":{"rendered":"2012-10-27 19.18.39 (1024&#215;576)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_crdt_document":""},"media_tag":[],"class_list":["post-94","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"filename":"2012-10-27-19.18.39-1024x576.jpg","filesize":371554,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a33SNi-1w","jetpack_likes_enabled":true,"description":{"rendered":"\r\n\t<!-- sfs forms added to the_content - adding as a comment so that it will not display, but will it fool spammers?\r\n\t<br>\r\n\t<br>\r\n\t<form action=\"https:\/\/westerntrailrider.com\/wordpress\/wp-comments-post.php\" method=\"post\" id=\"commentform1\">\r\n\t<p><input name=\"author\" id=\"author\" value=\"\" size=\"22\"  aria-required=\"true\" type=\"text\">\r\n\t<label for=\"author\"><small>Name (required)<\/small><\/label><\/p>\r\n\r\n\t<p><input name=\"email\" id=\"email\" value=\"\" size=\"22\"  aria-required=\"true\" type=\"text\">\r\n\t<label for=\"email\"><small>Mail (will not be published) (required)<\/small><\/label><\/p>\r\n\r\n\t<p><input name=\"url\" id=\"url\" value=\"\" size=\"22\" type=\"text\">\r\n\t<label for=\"url\"><small>Website<\/small><\/label><\/p>\r\n\t<p><textarea name=\"comment\" id=\"comment\" cols=\"58\" rows=\"10\" ><\/textarea><\/p>\r\n\r\n\t<p>\r\n\t<input name=\"comment_post_ID\" value=\"94\" id=\"comment_post_ID\" type=\"hidden\">\r\n\t<input name=\"comment_parent\" id=\"comment_parent\" value=\"0\" type=\"hidden\">\r\n\t<\/p>\r\n\r\n\t<p><input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"c99e9a5cfa\" type=\"hidden\"><\/p>\r\n\t<\/form>\r\n\r\n\t<form id=\"setupform1\" method=\"post\" action=\"wp-signup.php\" >\r\n\r\n\t<input type=\"hidden\" name=\"stage\" value=\"validate-user-signup\"   \/>\r\n\t<p ><input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"c99e9a5cfa\" type=\"hidden\"><\/p>\t\t\r\n\t<p>\r\n\t<input id=\"signupblog\" type=\"radio\" name=\"signup_for\" value=\"blog\"  checked='checked' \/>\r\n\t<label class=\"checkbox\" for=\"signupblog\">Gimme a site!<\/label>\r\n\t<br \/>\r\n\t<input id=\"signupuser\" type=\"radio\" name=\"signup_for\" value=\"user\"  \/>\r\n\t<label class=\"checkbox\" for=\"signupuser\">Just a username, please.<\/label>\r\n\t<\/p>\r\n\t<\/form>\r\n\r\n\t<form name=\"loginform1\" id=\"loginform1\" action=\"https:\/\/westerntrailrider.com\/wordpress\/wp-login.php\" method=\"post\">\r\n\t<p>\r\n\t<label for=\"user_login\">User Name<br \/>\r\n\t<input type=\"text\" name=\"log\"  value=\"\" size=\"20\"  \/><\/label>\r\n\t<\/p>\r\n\t<p>\r\n\t<label for=\"user_pass\">Password<br \/>\r\n\t<input type=\"password\" name=\"pwd\"  value=\"\" size=\"20\"  \/><\/label>\r\n\t<\/p>\r\n\t<p class=\"forgetmenot\"><label for=\"rememberme\"><input name=\"rememberme\" type=\"checkbox\" checked=\"checked\"  value=\"c99e9a5cfa\"  \/>Remember Me<\/label><\/p>\r\n\t<p class=\"submit\">\r\n\t<input type=\"hidden\" name=\"testcookie\" value=\"1\" \/>\r\n\t<\/p>\r\n\t<input id=\"akismet_comment_nonce\" name=\"akismet_comment_nonce\" value=\"c99e9a5cfa\" type=\"hidden\">\r\n\t<\/form>\r\n\r\n\r\n\r\n\t-->\r\n\t<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?fit=300%2C168&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?resize=624%2C351&amp;ssl=1 624w, https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?w=948&amp;ssl=1 948w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"94\" data-permalink=\"https:\/\/westerntrailrider.com\/wordpress\/2012-10-27-19-18-39-1024x576\/\" data-orig-file=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?fit=1024%2C576&amp;ssl=1\" data-orig-size=\"1024,576\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;MB855&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1351365519&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.73&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0666&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"2012-10-27 19.18.39 (1024&amp;#215;576)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;17&amp;#8243; swells and a brass horn&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?fit=474%2C267&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>17&#8243; swells and a brass horn<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":576,"file":"2013\/02\/2012-10-27-19.18.39-1024x576.jpg","sizes":{"thumbnail":{"file":"2012-10-27-19.18.39-1024x576-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"2012-10-27-19.18.39-1024x576-300x168.jpg","width":300,"height":168,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?fit=300%2C168&ssl=1"},"post-thumbnail":{"file":"2012-10-27-19.18.39-1024x576-624x351.jpg","width":624,"height":351,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?resize=624%2C351&ssl=1"},"full":{"file":"2012-10-27-19.18.39-1024x576.jpg?fit=1024%2C576&ssl=1","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg?fit=1024%2C576&ssl=1"}},"image_meta":{"aperture":2.6000000000000001,"credit":"","camera":"MB855","caption":"","created_timestamp":1351365519,"copyright":"","focal_length":"4.73","iso":"400","shutter_speed":"0.0666","title":""}},"post":null,"source_url":"https:\/\/westerntrailrider.com\/wordpress\/wp-content\/uploads\/2013\/02\/2012-10-27-19.18.39-1024x576.jpg","jetpack_videopress_guid":"","jetpack_videopress":{"title":"2012-10-27 19.18.39 (1024x576)","description":"","caption":"17\" swells and a brass horn","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/comments?post=94"}],"wp:term":[{"taxonomy":"media_tag","embeddable":true,"href":"https:\/\/westerntrailrider.com\/wordpress\/wp-json\/wp\/v2\/media_tag?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}